{"id":26344,"date":"2024-12-19T08:00:46","date_gmt":"2024-12-19T07:00:46","guid":{"rendered":"https:\/\/web.lasallesantiago.gal\/cual-es-el-pais-mas-rico-del-mundo\/"},"modified":"2024-12-19T08:01:06","modified_gmt":"2024-12-19T07:01:06","slug":"cual-es-el-pais-mas-rico-del-mundo","status":"publish","type":"post","link":"https:\/\/web.lasallesantiago.gal\/es\/cual-es-el-pais-mas-rico-del-mundo\/","title":{"rendered":"\u00bfCu\u00e1l es el pa\u00eds m\u00e1s rico del mundo?"},"content":{"rendered":"\n<p>Con motivo del programa Ponte recibimos en las aulas de Econom\u00eda de 1.\u00ba de Bachillerato al profesor de Administraci\u00f3n de Empresa de la USC Adri\u00e1n Dios. La pregunta de partida nos hac\u00eda pensar en qu\u00e9 es la riqueza y c\u00f3mo medirla. En una sesi\u00f3n muy participada por el alumnado, Adri\u00e1n fue desmenuzando los conceptos del PIB, de la renta per c\u00e1pita, el IDH&#8230; para acabar recalando en la inflaci\u00f3n y su impacto en nuestras vidas. Muchas gracias profesor, siempre es una riqueza poder disponer del tiempo, los conocimientos y la cercan\u00eda de los dem\u00e1s.   <\/p>\n\n<p>\u00a1Hasta la pr\u00f3xima!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con motivo del programa Ponte recibimos en las aulas de Econom\u00eda de 1.\u00ba de Bachillerato al profesor de Administraci\u00f3n de Empresa de la USC Adri\u00e1n Dios. La pregunta de partida nos hac\u00eda pensar en qu\u00e9 es la riqueza y c\u00f3mo &hellip; <\/p>\n","protected":false},"author":1,"featured_media":26342,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[81,100],"tags":[],"class_list":["post-26344","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-bachillerato"],"_links":{"self":[{"href":"https:\/\/web.lasallesantiago.gal\/es\/wp-json\/wp\/v2\/posts\/26344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.lasallesantiago.gal\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.lasallesantiago.gal\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.lasallesantiago.gal\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/web.lasallesantiago.gal\/es\/wp-json\/wp\/v2\/comments?post=26344"}],"version-history":[{"count":3,"href":"https:\/\/web.lasallesantiago.gal\/es\/wp-json\/wp\/v2\/posts\/26344\/revisions"}],"predecessor-version":[{"id":26347,"href":"https:\/\/web.lasallesantiago.gal\/es\/wp-json\/wp\/v2\/posts\/26344\/revisions\/26347"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.lasallesantiago.gal\/es\/wp-json\/wp\/v2\/media\/26342"}],"wp:attachment":[{"href":"https:\/\/web.lasallesantiago.gal\/es\/wp-json\/wp\/v2\/media?parent=26344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.lasallesantiago.gal\/es\/wp-json\/wp\/v2\/categories?post=26344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.lasallesantiago.gal\/es\/wp-json\/wp\/v2\/tags?post=26344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}