{"id":9055,"date":"2020-05-13T08:11:20","date_gmt":"2020-05-13T08:11:20","guid":{"rendered":"https:\/\/web.lasallesantiago.gal\/?page_id=9055"},"modified":"2025-07-15T21:06:15","modified_gmt":"2025-07-15T19:06:15","slug":"actividades-extraescolares","status":"publish","type":"page","link":"https:\/\/web.lasallesantiago.gal\/es\/actividades-extraescolares\/","title":{"rendered":"Actividades extraescolares"},"content":{"rendered":"<div id=\"pl-9055\"  class=\"panel-layout\" ><div id=\"pg-9055-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-9055-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-9055-0-0-0\" class=\"so-panel widget widget_heading panel-first-child panel-last-child\" data-index=\"0\" ><div class=\"thim-widget-heading template-base\"><div class=\"sc_heading  text-left\"><h3 style=\"text-transform: uppercase;\" class=\"title\">Actividades extraescolares<\/h3><p class=\"sub-heading\" style=\"\"><h4 class=\"texto-azul\">Actividades extraescolares del curso  2025\/26.<\/h4>  \n<h4 class=\"texto-azul\">El lunes 19 de septiembre se abrir\u00e1 un curso  en SALLENET \"Actividades Extraescolares\" para poder realizar las inscripciones hasta el 26 de septiembre. <\/h4><\/p><span class=\"line\"><\/span><\/div><\/div><\/div><\/div><\/div><div id=\"pg-9055-1\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-9055-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-9055-1-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child\" data-index=\"1\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t><h3 class=\"widget-title\">Pastorales<\/h3>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<\/div>\n<\/div><\/div><div id=\"panel-9055-1-0-1\" class=\"so-panel widget widget_tab panel-last-child\" data-index=\"2\" ><div class=\"thim-widget-tab template-tab\">\n<ul class=\"nav nav-tabs\" role=\"tablist\"><li role=\"presentation\" class='active tab-col-3'><a href=\"#thim-widget-tab-11778701246-1-74\"  role=\"tab\" data-toggle=\"tab\">SalleXove - Grupos Cristianos<\/a><\/li><li role=\"presentation\" class='tab-col-3'><a href=\"#thim-widget-tab-21778701246-1-74\"  role=\"tab\" data-toggle=\"tab\">SalleXove - Voluntariado - Plan de Acci\u00f3n Social<\/a><\/li><li role=\"presentation\" class='tab-col-3'><a href=\"#thim-widget-tab-31778701246-1-74\"  role=\"tab\" data-toggle=\"tab\">SalleXove - Proyde y Comercio Justo<\/a><\/li><\/ul><div class=\"tab-content\"> <div role=\"tabpanel\" class=\"tab-pane active\" id=\"thim-widget-tab-11778701246-1-74\">Destinatarios Alumnos de 5.\u00ba y 6.\u00ba de Primaria, Secundaria y Bachillerato. Antiguos alumnos universitarios. Objetivos Iniciar en la vivencia personal de la fe y el conocimiento de la figura de Jes\u00fas. Promover un desarrollo personal integrador, basado en experiencias constructivas, vividas en grupo, que potencien valores como la solidaridad, la autenticidad y la amistad. Actividades que se desarrollan Reuni\u00f3n semanal del Grupo con el animador. Encuentros con otros Grupos del colegio y del Sector. Colonias, Campamentos y Encuentros de verano. Pascua Juvenil, Encuentro de Oraci\u00f3n, Voluntariado, Campos de trabajo... (seg\u00fan edades) Salidas y acampadas. D\u00edas y horas De octubre a junio, una reuni\u00f3n semanal. De 5.\u00ba de Primaria a 2.\u00ba ESO: viernes de 15:00 a 16:00 h De 3.\u00ba ESO en adelante, el d\u00eda y la hora la decide cada grupo, preferentemente los viernes por la tarde. Material necesario - Responsable Mar\u00eda Chao (Delegada de Pastoral Extracurricular) y Equipo de Animadores. Coste Actividad gratuita, excepto salidas y encuentros a los que se asista. Para participar La inscripci\u00f3n se realizar\u00e1 a trav\u00e9s del formulario disponible en Sallenet. Ser fiel a las reuniones semanales y a los encuentros.<\/div> <div role=\"tabpanel\" class=\"tab-pane\" id=\"thim-widget-tab-21778701246-1-74\">Destinatarios Alumnos de 4.\u00ba de ESO y Bachillerato. Actividad abierta tambi\u00e9n a los padres y profesores que lo deseen. Objetivos Dedicar voluntariamente parte de nuestro tiempo al trabajo con personas en riesgo de exclusi\u00f3n social. Favorecer el crecimiento personal a trav\u00e9s del contacto e intercambio con personas de otras culturas, situaci\u00f3n social, circunstancias vitales, etc, viviendo valores como la solidaridad y la amistad. Actividades que se desarrollan Una hora semanal en alguna de las siguientes actividades: apoyo escolar y ludoteca, trabajo con inmigrantes, actividades con personas discapacitadas, acompa\u00f1amiento a ancianos y gente sin hogar, atenci\u00f3n del punto de venta de Comercio Justo del colegio. D\u00edas y horas Los participantes tienen la posibilidad de elegir el d\u00eda y la hora que mejor se ajusten a sus posibilidades, a partir de los horarios que nos ofrecen las organizaciones con quienes colaboramos. De octubre a mayo. Material necesario - Responsable Amalia Soneira (Delegada de Justicia) y Equipo de Educaci\u00f3n en la Justicia. Coste Actividad gratuita. Para participar Responder a la convocatoria que se hace al principio del curso. Ser constante en el compromiso que se adquiera.<\/div> <div role=\"tabpanel\" class=\"tab-pane\" id=\"thim-widget-tab-31778701246-1-74\">Destinatarios Alumnos de ESO y Bachillerato. Actividad abierta tambi\u00e9n a los padres y profesores que lo deseen. Objetivos Animar el punto de venta de Comercio Justo en el colegio y en actividades puntuales de Comercio Justo en la ciudad. Reflexionar sobre la importancia del Comercio Justo y h\u00e1bitos de consumo responsable en relaci\u00f3n con los pa\u00edses empobrecidos del planeta. Colaborar en la campa\u00f1a anual de sensibilizaci\u00f3n organizada por la ONGD PROYDE y en acciones de financiaci\u00f3n para proyectos de Desarrollo. Participar en un voluntariado internacional (seg\u00fan edades). Actividades que se desarrollan Reuni\u00f3n cuando se convoque la Asamblea. Animaci\u00f3n de actividades colegiales para la financiaci\u00f3n de proyectos de PROYDE. Participaci\u00f3n en actividades organizadas en favor de PROYDE y del Comercio Justo. D\u00edas y horas Se decidir\u00e1n en funci\u00f3n de las posibilidades de los participantes. Material necesario - Responsable Amalia Soneira (Delegada de Justicia) y Equipo de Educaci\u00f3n en la Justicia. Coste Actividad gratuita. Para participar Responder a la convocatoria que se hace al principio del curso. Ser constante en el compromiso que se adquiera.<\/div><\/div><\/div><\/div><\/div><\/div><div id=\"pg-9055-2\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-9055-2-0\"  class=\"panel-grid-cell\" ><div id=\"panel-9055-2-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child\" data-index=\"3\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t><h3 class=\"widget-title\">Deportivas<\/h3>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<\/div>\n<\/div><\/div><div id=\"panel-9055-2-0-1\" class=\"so-panel widget widget_tab panel-last-child\" data-index=\"4\" ><div class=\"thim-widget-tab template-tab\">\n<ul class=\"nav nav-tabs\" role=\"tablist\"><li role=\"presentation\" class='active tab-col-6'><a href=\"#thim-widget-tab-11778701246-1-7\"  role=\"tab\" data-toggle=\"tab\">Patinaje<\/a><\/li><li role=\"presentation\" class='tab-col-6'><a href=\"#thim-widget-tab-21778701246-1-7\"  role=\"tab\" data-toggle=\"tab\">Judo<\/a><\/li><li role=\"presentation\" class='tab-col-6'><a href=\"#thim-widget-tab-31778701246-1-7\"  role=\"tab\" data-toggle=\"tab\">K\u00e1rate<\/a><\/li><li role=\"presentation\" class='tab-col-6'><a href=\"#thim-widget-tab-41778701246-1-7\"  role=\"tab\" data-toggle=\"tab\">Predeporte<\/a><\/li><li role=\"presentation\" class='tab-col-6'><a href=\"#thim-widget-tab-51778701246-1-7\"  role=\"tab\" data-toggle=\"tab\">Esgrima hist\u00f3rica<\/a><\/li><li role=\"presentation\" class='tab-col-6'><a href=\"#thim-widget-tab-61778701246-1-7\"  role=\"tab\" data-toggle=\"tab\">Ajedrez<\/a><\/li><\/ul><div class=\"tab-content\"> <div role=\"tabpanel\" class=\"tab-pane active\" id=\"thim-widget-tab-11778701246-1-7\">Destinatarios Alumnos del colegio y externos desde Infantil a 4.\u00ba de la ESO. Objetivos Desarrollo de las capacidades f\u00edsicas y motrices (equilibrios, flexibilidad y conocimiento del cuerpo). Actividades que se desarrollan Dos sesiones semanales de una hora en el colegio (patio cubierto y polideportivo). D\u00edas y horas Lunes y mi\u00e9rcoles: 17:00 a 18:00 h (Grupo Iniciaci\u00f3n 1\u00ba, 2\u00ba, 3\u00ba Ed p y alumnado de otros cursos que no tenga varios a\u00f1os de experiencia) Lunes y mi\u00e9rcoles: 18:00 a 19:00 h (Grupo Intermedio 4\u00ba, 5\u00ba y 6\u00ba Ed p con experiencia) Martes y jueves: 17:00 a 18:00 h (Grupo Infantil) Martes y jueves: 18:00 a 19:00 h (Grupo Avanzado 6\u00ba Ed p y secundaria) Material necesario Patines de bota y de dos ejes, dos ruedas adelante y dos atr\u00e1s, con taco en punta. Responsable Iria G\u00f3mez Santos (4 grupos). Alba Lamas Estev\u00e9z (2 grupos). Coste 30 \u20ac de mensualidad Para participar Inscripci\u00f3n a trav\u00e9s del enlace de sallenet , cumplimentando cada uno de los apartados. Participaci\u00f3n en el campeonato escolar y en el festival de patinaje del colegio. PLAZAS LIMITADAS EN TODOS LOS GRUPOS<\/div> <div role=\"tabpanel\" class=\"tab-pane\" id=\"thim-widget-tab-21778701246-1-7\">Destinatarios Alumnos del colegio y externos desde de Primaria. Objetivos La formaci\u00f3n a trav\u00e9s del deporte, favoreciendo su desarrollo corporal, la coordinaci\u00f3n, el control de la agresividad y el desarrollo muscular arm\u00f3nico. Preparaci\u00f3n para una mejor adaptaci\u00f3n a nuestra sociedad. Actividades que se desarrollan Dos sesiones semanales de una hora de entrenamiento en el colegio. Participaci\u00f3n en actividades organizadas por la Federaci\u00f3n y el Club (campeonatos, concentraciones, festivales, campamentos de verano, etc.). D\u00edas y horas Lunes y mi\u00e9rcoles: 17:00 a 18:00 h (1\u00ba,2\u00ba y 3\u00ba de primaria) Lunes y mi\u00e9rcoles: 18:00 a 19:00 h (4\u00ba, 5\u00ba, 6\u00ba de primaria y 1\u00ba ESO) Lunes y jueves: 19.00 a 20.00 h (Grupo intermedio ESO y Bachillerato) Lunes y jueves: 20.00 a 21.00 h (Grupo avanzado ESO, Bachillerato y externos) Viernes: 18:30 a 20:30 h (ESO, Bachillerato y externos) Material necesario Kimono de Judo. Responsable Manuel Mallo Dorado Nicol\u00e1s Garc\u00eda Cadet Coste 30 \u20ac de mensualidad. Licencia Federativa obligatoria (precio marcado por la Federaci\u00f3n). Da derecho a participar en todas las actividades federadas, al reconocimiento de los ex\u00e1menes de cintur\u00f3n y al seguro m\u00e9dico deportivo. Para participar Inscripci\u00f3n a trav\u00e9s del gestor (Sallenet).<\/div> <div role=\"tabpanel\" class=\"tab-pane\" id=\"thim-widget-tab-31778701246-1-7\">Destinatarios Alumnos del colegio y externos de Primaria. Objetivos La formaci\u00f3n a trav\u00e9s del deporte, favoreciendo su desarrollo, coordinaci\u00f3n, autoestima y disciplina personal. Actividades que se desarrollan Dos sesiones semanales de una hora de entrenamiento en el colegio. Participaci\u00f3n en actividades organizadas por la Federaci\u00f3n y el Club (campeonatos, concentraciones, festivales, etc.). D\u00edas y horas Martes y jueves: 17:00 a 18:00 h (1.\u00ba a 4.\u00ba de primaria). Martes y jueves: 18:00 a 19:00 h (5.\u00ba de primaria en adelante). Material necesario Karategui. (Obligatorio) Responsable Ainhoa Rodr\u00edguez Fern\u00e1ndez. Coste 30 \u20ac de mensualidad. Licencia Federativa obligatoria (precio marcado por la Federaci\u00f3n). Para participar Inscripci\u00f3n a trav\u00e9s del gestor, cumplimentando cada uno de los apartados teniendo especial atenci\u00f3n al apartado de la tarjeta sanitaria.<\/div> <div role=\"tabpanel\" class=\"tab-pane\" id=\"thim-widget-tab-41778701246-1-7\">Destinatarios Alumnos del colegio de Educaci\u00f3n Infantil. Objetivos A trav\u00e9s del predeporte y los movimientos queremos desarrollar la coordinaci\u00f3n corporal, la relaci\u00f3n y la comunicaci\u00f3n social. Actividades que se desarrollan Dos sesiones semanales de una hora en el colegio (Aula Psicomotricidad). D\u00edas y horas Martes y jueves: 17:00 a 18:00 h Material necesario - Responsable Nicol\u00e1s Garc\u00eda Cadet Coste 30 \u20ac de mensualidad. Para participar Inscripci\u00f3n a trav\u00e9s del gestor (Sallent), cumplimentando cada uno de los apartados.<\/div> <div role=\"tabpanel\" class=\"tab-pane\" id=\"thim-widget-tab-51778701246-1-7\">Destinatarios Alumnos de Secundaria y Bachillerato Objetivos Investigaci\u00f3n, recuperaci\u00f3n y puesta en pr\u00e1ctica de las t\u00e9cnicas de lucha europeas de arma blanca de los siglos XV a XVII. Respeto al rival y al profesor, as\u00ed como confianza en los compa\u00f1eros y voluntad de superaci\u00f3n propia. Mejorar el aparato locomotor, fortalecer la musculatura e incrementar la flexibilidad. Desarrollar la capacidad de concentraci\u00f3n, aumentar el compa\u00f1erismo y respeto por los dem\u00e1s y aprender a ser disciplinados y adaptables a distintas situaciones. Actividades que se desarrollan Estudio de diferentes tratados de esgrima, la evoluci\u00f3n de las armas y los movimientos del cuerpo. Acercamiento al uso del lat\u00edn, italiano medieval y castellano del siglo XVII Ejercicios t\u00e9cnicos y espec\u00edficos de las artes marciales europeas (piernas, desplazamientos... y coordinaci\u00f3n de todo el cuerpo). Combates con las diversas armas. D\u00edas y horas Jueves a las 16:00 h Material necesario El material ser\u00e1 proporcionado por el monitor y la Academia de Espada (2 m\u00e1scaras de esgrima, espadas de entrenamiento y palos). En los primeros niveles no ser\u00e1 necesario contar con guantes protectores, chaquetas de esgrima o petos... El material de investigaci\u00f3n y documentaci\u00f3n ser\u00e1 proporcionado tambi\u00e9n por el monitor. Responsable Pablo Cachafeiro Murias. Miembro de la Asociaci\u00f3n Ourens\u00e1 de Esgrima Antiga. Coste 19 \u20ac de mensualidad. Para participar Los grupos tendr\u00e1n un m\u00ednimo de 10 alumnos y un m\u00e1ximo de 16. La inscripci\u00f3n se realizar\u00e1 a trav\u00e9s del formulario disponible en Sallenet.<\/div> <div role=\"tabpanel\" class=\"tab-pane\" id=\"thim-widget-tab-61778701246-1-7\">Destinatarios Alumnos del colegio de Educaci\u00f3n Primaria. Objetivos Disfrutar con un juego de l\u00f3gica, donde la atenci\u00f3n y el razonamiento son instrumentos imprescindibles para el desenvolvimiento de las jugadas. Actividades que se desarrollan Dos sesiones semanales de una hora en el colegio (Aula Pl\u00e1stica de Infantil). D\u00edas y horas Lunes y mi\u00e9rcoles: 13:40 a 14:40 h Material necesario Responsable Juan Roberto Pati\u00f1o Romar\u00eds. Coste 30\u20ac de mensualidad. Para participar Inscripci\u00f3n a trav\u00e9s del gestor (SALLENET, cumplimentando cada uno de los apartados.<\/div><\/div><\/div><\/div><\/div><\/div><div id=\"pg-9055-3\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-9055-3-0\"  class=\"panel-grid-cell\" ><div id=\"panel-9055-3-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child\" data-index=\"5\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t><h3 class=\"widget-title\">Art\u00edsticas<\/h3>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<\/div>\n<\/div><\/div><div id=\"panel-9055-3-0-1\" class=\"so-panel widget widget_tab\" data-index=\"6\" ><div class=\"thim-widget-tab template-tab\">\n<ul class=\"nav nav-tabs\" role=\"tablist\"><li role=\"presentation\" class='active tab-col-5'><a href=\"#thim-widget-tab-11778701246-1-74\"  role=\"tab\" data-toggle=\"tab\">Urban dance<\/a><\/li><li role=\"presentation\" class='tab-col-5'><a href=\"#thim-widget-tab-21778701246-1-74\"  role=\"tab\" data-toggle=\"tab\">Gimnasia R\u00edtmica<\/a><\/li><li role=\"presentation\" class='tab-col-5'><a href=\"#thim-widget-tab-31778701246-1-74\"  role=\"tab\" data-toggle=\"tab\">Baile Moderno<\/a><\/li><li role=\"presentation\" class='tab-col-5'><a href=\"#thim-widget-tab-41778701246-1-74\"  role=\"tab\" data-toggle=\"tab\">Baile Gallego<\/a><\/li><li role=\"presentation\" class='tab-col-5'><a href=\"#thim-widget-tab-51778701246-1-74\"  role=\"tab\" data-toggle=\"tab\">Ballet<\/a><\/li><\/ul><div class=\"tab-content\"> <div role=\"tabpanel\" class=\"tab-pane active\" id=\"thim-widget-tab-11778701246-1-74\">Destinatarios Alumnos del colegio Secundaria, Bachillerato y externos Objetivos Ayudar a desarrollar un estilo de vida saludable a trav\u00e9s de un entrenamiento divertido. Aprender a improvisar movimientos fomentando la interacci\u00f3n y el contacto con los espectadores y otros bailarines. Incorporar valores claves para el desarrollo de los chicos, tales como respeto, trabajo en equipo, confianza, autoestima, memoria, creatividad, coordinaci\u00f3n y conciencia cultural. Actividades que se desarrollan Conocimiento t\u00e9cnico de las danzas urbanas. Expresi\u00f3n y trabajo corporal. Bailar los ritmos m\u00e1s actuales como el Hip Hop, Funky, House, Dance Hall, Locking, Street Dance, Break Dance, Wacking, Hype, Pooping... Participaci\u00f3n en festivales del colegio y otras competiciones. D\u00edas y horas Martes y jueves: 16.00 a 17.00 h Material necesario Ropa y calzado c\u00f3modo adaptado a la actividad, as\u00ed como botella de agua y toalla si fuese necesario. Responsable Jacobo Franco Garc\u00eda Coste 30\u20ac de mensualidad. Para participar La inscripci\u00f3n se realizar\u00e1 a trav\u00e9s del formulario disponible en Sallenet.<\/div> <div role=\"tabpanel\" class=\"tab-pane\" id=\"thim-widget-tab-21778701246-1-74\">Destinatarios Alumnos del colegio de la etapa de Educaci\u00f3n Primaria. Objetivos La combinaci\u00f3n del ballet, gimnasia r\u00edtmica y danza como actividades saludables, divertidas y propicias para obtener una coordinaci\u00f3n expresiva est\u00e9tica del cuerpo. Actividades que se desarrollan Dos sesiones semanales de una hora en el colegio (Aula Psicomotricidad). D\u00edas y horas Lunes y mi\u00e9rcoles: 17:00 a 18:00 h Material necesario - Responsable Club Gimnasia R\u00edtmica Compostela. Coste 30 \u20ac de mensualidad. Licencia Federativa obligatoria (precio marcado por la Federaci\u00f3n). Para participar Inscripci\u00f3n a trav\u00e9s del gestor, cumplimentando cada uno de los apartado.<\/div> <div role=\"tabpanel\" class=\"tab-pane\" id=\"thim-widget-tab-31778701246-1-74\">Destinatarios Alumnos del colegio de la etapa de Educaci\u00f3n Infantil y Educaci\u00f3n Primaria.. Objetivos Ayudar a desarrollar un estilo de vida saludable a trav\u00e9s de un entrenamiento divertido. Aprender a improvisar movimientos fomentando la interacci\u00f3n y el contacto con los espectadores y otros bailarines. Incorporar valores claves para el desarrollo de los ni\u00f1os, tales como respeto, trabajo en equipo, confianza, autoestima, memoria, creatividad, coordinaci\u00f3n y conciencia cultural. Actividades que se desarrollan Dos sesiones semanales de una hora en el colegio (Aula Polivalente). D\u00edas y horas Lunes y mi\u00e9rcoles: 17:00 a 18:00 h Martes y jueves: 17:00 a 18:00 h Material necesario Ropa c\u00f3moda Responsable Luc\u00eda V\u00e1zquez Fandi\u00f1o. Carlos Casal Blanco. Coste 30 \u20ac de mensualidad Para participar Inscripci\u00f3n a trav\u00e9s del gestor, cumplimentando cada uno de los apartado.<\/div> <div role=\"tabpanel\" class=\"tab-pane\" id=\"thim-widget-tab-41778701246-1-74\">Destinatarios Alumnos del colegio y externos para la etapa de Primaria. Objetivos Experimentaci\u00f3n y diversi\u00f3n con las danzas tradicionales gallegas como herramienta de aprendizaje. Actividades que se desarrollan Una sesi\u00f3n semanal de dos horas en el colegio (Aula de psicomotricidad). D\u00edas y horas Viernes: 15:00 a 17:00h Material necesario Responsable Andrea Castro Rodr\u00edguez Coste 30 \u20ac de mensualidad. Para participar Inscripci\u00f3n a trav\u00e9s del gestor, cumplimentando cada uno de los apartados.<\/div> <div role=\"tabpanel\" class=\"tab-pane\" id=\"thim-widget-tab-51778701246-1-74\">Destinatarios Alumnos del colegio de la etapa de Educaci\u00f3n Primaria. Objetivos Ayudar a desarrollar un estilo de vida saludable a trav\u00e9s de un entrenamiento divertido. Incorporar valores claves para el desarrollo de los ni\u00f1os, tales como respeto, trabajo en equipo, confianza, autoestima, memoria, creatividad y conciencia cultural. Contribuye a corregir malas posturas, ganan elasticidad, ejercitan la coordinaci\u00f3n, la agilidad de movimiento y el equilibrio. Actividades que se desarrollan Dos sesiones semanales de una hora en el colegio (Aula Polivalente). D\u00edas y horas Martes y jueves: 17:00 a 18:00 h Material necesario - Responsable Sara Mun\u00edn Doce Coste 30 \u20ac de mensualidad. Para participar Inscripci\u00f3n a trav\u00e9s del gestor, cumplimentando cada uno de los apartado.<\/div><\/div><\/div><\/div><div id=\"panel-9055-3-0-2\" class=\"so-panel widget widget_tab panel-last-child\" data-index=\"7\" ><div class=\"thim-widget-tab template-tab\">\n<ul class=\"nav nav-tabs\" role=\"tablist\"><li role=\"presentation\" class='active tab-col-4'><a href=\"#thim-widget-tab-11778701246-1-98\"  role=\"tab\" data-toggle=\"tab\">Taller de teatro<\/a><\/li><li role=\"presentation\" class='tab-col-4'><a href=\"#thim-widget-tab-21778701246-1-98\"  role=\"tab\" data-toggle=\"tab\"><\/a><\/li><li role=\"presentation\" class='tab-col-4'><a href=\"#thim-widget-tab-31778701246-1-98\"  role=\"tab\" data-toggle=\"tab\">Artes Pl\u00e1sticas<\/a><\/li><li role=\"presentation\" class='tab-col-4'><a href=\"#thim-widget-tab-41778701246-1-98\"  role=\"tab\" data-toggle=\"tab\">M\u00fasica (m\u00e9todo Suzuki)<\/a><\/li><\/ul><div class=\"tab-content\"> <div role=\"tabpanel\" class=\"tab-pane active\" id=\"thim-widget-tab-11778701246-1-98\">Destinatarios Alumnos de Primaria. Objetivos Adquirir conocimientos te\u00f3ricos y pr\u00e1cticos relacionados con el teatro. Potenciar habilidades sociales y emocionales. Memorizar textos sencillos y adquirir capacidades interpretativas y de improvisaci\u00f3n. Fomentar actitudes, t\u00e9cnicas y habilidades necesarias para utilizar el juego dram\u00e1tico como un instrumento pedag\u00f3gico. Potenciar el desarrollo corporal y f\u00edsico a trav\u00e9s de distintas din\u00e1micas, ejercicios, juegos\u2026 Aprender a escuchar, respetar a los compa\u00f1eros, atender a ordenes... Actividades que se desarrollan Actividades de respiraci\u00f3n, fonolog\u00eda, relajaci\u00f3n, concentraci\u00f3n, improvisaciones\u2026 Representar peque\u00f1os papeles, escenificar y realizar montajes teatrales (obras, musicales, t\u00edteres...) Realizar juegos y actividades dram\u00e1ticas (ponerse en distintas situaciones e improvisar). Teatro de t\u00edteres, gui\u00f1oles, sombras... Montaje teatral y creaci\u00f3n de decorados. Actividades que favorecen la expresi\u00f3n oral, comunicaci\u00f3n. Representaci\u00f3n de una obra de teatro. D\u00edas y horas Viernes: 16:00 a 17:00 h Material necesario - Responsable Andrea Rodr\u00edguez y Mariqui\u00f1a Pereira. Coste 19 \u20ac de mensualidad Para participar Los grupos tendr\u00e1n un m\u00ednimo de 10 alumnos. La inscripci\u00f3n se realizar\u00e1 a trav\u00e9s del formulario disponible en Sallenet.<\/div> <div role=\"tabpanel\" class=\"tab-pane\" id=\"thim-widget-tab-21778701246-1-98\"><\/div> <div role=\"tabpanel\" class=\"tab-pane\" id=\"thim-widget-tab-31778701246-1-98\">Destinatarios Alumnos del colegio y externos para la etapa de Primaria. Objetivos Aprender a usar materiales de deshecho para la construcci\u00f3n de obras pl\u00e1sticas. Estimular el inter\u00e9s por la pintura y las creaciones pl\u00e1sticas. Actividades que se desarrollan Dos sesiones semanales de una hora en el colegio (Aula de Pl\u00e1stica de la ESO en el primer piso). D\u00edas y horas Martes y jueves (17:00 a 18:00 h) Material necesario - Responsable Y\u00e9sica P\u00e1jaro Mallo. Coste 30 \u20ac de mensualidad. Para participar Inscripci\u00f3n a trav\u00e9s del gestor, cumplimentando cada uno de los apartados.<\/div> <div role=\"tabpanel\" class=\"tab-pane\" id=\"thim-widget-tab-41778701246-1-98\">Destinatarios Alumnos del colegio de la Etapa de Infantil y 1\u00ba de Primaria. Objetivos Aprendizaje de la m\u00fasica a trav\u00e9s de la pr\u00e1ctica con los instrumentos. Actividades que se desarrollan Una sesi\u00f3n semanal de una hora. (Aula Polivalente y aula de M\u00fasica de Primaria). D\u00edas y horas Lunes (Grupo A Infantil): 13:35-14:35 h Martes (Grupo B Infantil): 13:35-14:35 h Jueves (Grupo 1.\u00ba Primaria): 13:35-14:35 h Material necesario Violines, Teclados (Los aporta la profesora). Responsable Noelia L\u00f3pez Fern\u00e1ndez. Coste 22 \u20ac de mensualidad Para participar Inscripci\u00f3n a trav\u00e9s del gestor, cumplimentando cada uno de los apartados. Grupos de 11 alumnos como m\u00e1ximo (por cuestiones materiales).<\/div><\/div><\/div><\/div><\/div><\/div><div id=\"pg-9055-4\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-9055-4-0\"  class=\"panel-grid-cell\" ><div id=\"panel-9055-4-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child\" data-index=\"8\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t><h3 class=\"widget-title\">Acad\u00e9micas<\/h3>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<\/div>\n<\/div><\/div><div id=\"panel-9055-4-0-1\" class=\"so-panel widget widget_tab panel-last-child\" data-index=\"9\" ><div class=\"thim-widget-tab template-tab\">\n<ul class=\"nav nav-tabs\" role=\"tablist\"><li role=\"presentation\" class='active tab-col-4'><a href=\"#thim-widget-tab-11778701246-1-42\"  role=\"tab\" data-toggle=\"tab\">Mecanograf\u00eda<\/a><\/li><li role=\"presentation\" class='tab-col-4'><a href=\"#thim-widget-tab-21778701246-1-42\"  role=\"tab\" data-toggle=\"tab\">Rob\u00f3tica 1<\/a><\/li><li role=\"presentation\" class='tab-col-4'><a href=\"#thim-widget-tab-31778701246-1-42\"  role=\"tab\" data-toggle=\"tab\">Rob\u00f3tica 2<\/a><\/li><li role=\"presentation\" class='tab-col-4'><a href=\"#thim-widget-tab-41778701246-1-42\"  role=\"tab\" data-toggle=\"tab\">T\u00e9cnicas de Estudio<\/a><\/li><\/ul><div class=\"tab-content\"> <div role=\"tabpanel\" class=\"tab-pane active\" id=\"thim-widget-tab-11778701246-1-42\"><h4 class=\"texto-azul\">Destinatarios<\/h4>\nAlumnos del colegio de la Etapa de Primaria.\n<br>\n<h4 class=\"texto-azul\">Objetivos<\/h4>\nAprender el proceso de introducir textos o caracteres alfanum\u00e9ricos en un dispositivo por medio de un teclado.\n<br>\n<h4 class=\"texto-azul\">Actividades que se desarrollan<\/h4>\nDos sesiones semanales de una hora. (Aula de Inform\u00e1tica 2).\n<br>\n<h4 class=\"texto-azul\">D\u00edas y horas<\/h4>\nLunes y mi\u00e9rcoles: 13:35 - 14:35 h\n<br>\nMartes y jueves: 13:35 - 14:35 h\n<br>\n<h4 class=\"texto-azul\">Material necesario<\/h4>\nLicencia inform\u00e1tica proporcionada por el centro\n<br>\n<h4 class=\"texto-azul\">Responsable<\/h4>\nJaime Mansilla Chao\n<br>\n<h4 class=\"texto-azul\">Coste<\/h4>\n30 \u20ac de mensualidad<br>\n<br>\n<h4 class=\"texto-azul\">Para participar<\/h4>\nLos grupos tendr\u00e1n un m\u00ednimo de 10 alumnos y un m\u00e1ximo de 25.\nLa inscripci\u00f3n se realizar\u00e1 a trav\u00e9s del formulario disponible en Sallenet.\n<br><\/div> <div role=\"tabpanel\" class=\"tab-pane\" id=\"thim-widget-tab-21778701246-1-42\"><h4 class=\"texto-azul\">Destinatarios<\/h4>\nAlumnos de Primaria.\n<br>\n<h4 class=\"texto-azul\">Objetivos<\/h4>\nDesarrollar las competencias STEM.<br>\n- Iniciar a los participantes en el mundo de la rob\u00f3tica.<br>\n- Profundizar en el conocimiento de los sistemas de sensores y actuadores, sistemas de control y robots m\u00f3viles.<br>\n- Desarrollar el pensamiento computacional<br>\n- Aprender a resolver problemas de forma creativa.<br>\n- Trabajar el razonamiento espacial.<br>\n- Desarrollar habilidades cognitivas tales como la l\u00f3gica, la resoluci\u00f3n de problemas, la capacidad de an\u00e1lisis...<br>\n- Desarrollar competencias como la creatividad, la innovaci\u00f3n, la comunicaci\u00f3n, el esp\u00edritu emprendedor, la superaci\u00f3n de retos...<br>\n- Fomentar el trabajo en equipo, la cooperaci\u00f3n y el liderazgo.\n<br>\n<h4 class=\"texto-azul\">Actividades que se desarrollan<\/h4>\n- Trabajo con robots fischertechnik, productos que destacan por su calidad, nivel de desarrollo t\u00e9cnico, facilidad de uso y m\u00e1ximo aprovechamiento, as\u00ed como por sus resultados.<br>\n- Programaci\u00f3n mediante diagramas de flujo con el software RoboPro. El intercambio de datos entre los m\u00f3dulos de software y las subrutinas tiene lugar no solo mediante variables, sino tambi\u00e9n mediante conexiones gr\u00e1ficas. \n- Programaci\u00f3n en Scratch.<br>\n- Actividades de dise\u00f1o e impresi\u00f3n 3D.<br>\n- Trabajo con tecnolog\u00eda Makeblock compatible con Arduino y Harware Open Source.<br>\n- Actividades enfocadas a trabajar el pensamiento computacional y a desarrollar las competencias clave para su futuro profesional y personal.<br>\n- Los alumnos est\u00e1n agrupados en parejas y por niveles, de tal forma que siempre realizar\u00e1n las actividades con compa\u00f1eros con edades similares favoreciendo el aprendizaje y la participaci\u00f3n.<br>\n- Las tareas y roles definidos cambian cada sesi\u00f3n (ingeniero, constructor, programador). Esto permite un aprendizaje muy personalizado.<br>\n- Los profesores cumplen un doble perfil: experiencia t\u00e9cnica y pedag\u00f3gica. Esto permite que las actividades extraescolares sean divertidas, con buen clima de trabajo y con un nivel t\u00e9cnico elevado.\n<br>\n<h4 class=\"texto-azul\">D\u00edas y horas<\/h4>\nMi\u00e9rcoles de 17:00 a 18:00 h\n<br>\n<h4 class=\"texto-azul\">Material necesario<\/h4>\n- Material de fischertechnik (disponible)  - M\u00e1s informaci\u00f3n: <a class=\"icono enlace\" href=\"https:\/\/www.fischertechnik.de\/es-es\" target=\"_black\">www.fischertechnik.de<\/a><br>\n- Robots makeblock (disponible)\n<br>\n- Material Turing Tumble (disponible) - M\u00e1s informaci\u00f3n: <a class=\"icono enlace\" href=\"https:\/\/www.turingtumble.com\/\" target=\"_black\">www.turingtumble.com<\/a><br>\n- Ordenadores aula rob\u00f3tica (disponible)<br>\n- Software RoboPro (disponible)<br>\n- Software Scratch (disponible)<br>\n- Creality Ender 3 Impresora 3D (disponible) \n<br>\n<h4 class=\"texto-azul\">Responsable<\/h4>\nJos\u00e9 Antonio Mendui\u00f1a\n<br>\n<h4 class=\"texto-azul\">Coste<\/h4>\n30 \u20ac de mensualidad\n<br>\n<h4 class=\"texto-azul\">Para participar<\/h4>\nLos grupos tendr\u00e1n un m\u00ednimo de 10 alumnos y un m\u00e1ximo de 20.\nLa inscripci\u00f3n se realizar\u00e1 a trav\u00e9s del formulario disponible en Sallenet.\n<br><\/div> <div role=\"tabpanel\" class=\"tab-pane\" id=\"thim-widget-tab-31778701246-1-42\"><h4 class=\"texto-azul\">Destinatarios<\/h4>\nAlumnos Secundaria y Bachillerato.\n<br>\n<h4 class=\"texto-azul\">Objetivos<\/h4>\n- Desarrollar las competencias STEM.<br>\n- Iniciar a los participantes en el mundo de la rob\u00f3tica.<br>\n- Profundizar en el conocimiento de los sistemas de sensores y actuadores, sistemas de control y robots m\u00f3viles.<br>\n- Desarrollar el pensamiento computacional.<br>\n- Aprender a resolver problemas de forma creativa.<br>\n- Trabajar el razonamiento espacial.<br>\n- Desarrollar habilidades cognitivas tales como la l\u00f3gica, la resoluci\u00f3n de problemas, la capacidad de an\u00e1lisis...<br>\n- Desarrollar competencias como la creatividad, la innovaci\u00f3n, la comunicaci\u00f3n, el esp\u00edritu emprendedor, la superaci\u00f3n de retos...<br>\n- Fomentar el trabajo en equipo, la cooperaci\u00f3n y el liderazgo.\n<br>\n<h4 class=\"texto-azul\">Actividades que se desarrollan<\/h4>\n- Trabajo con robots <em>fischertechnik<\/em>, productos que destacan por su calidad, nivel de desarrollo t\u00e9cnico, facilidad de uso y m\u00e1ximo aprovechamiento, as\u00ed como por sus resultados.<br>\n- Programaci\u00f3n mediante diagramas de flujo con el software RoboPro. El intercambio de datos entre los m\u00f3dulos de software y las subrutinas tiene lugar no solo mediante variables, sino tambi\u00e9n mediante conexiones gr\u00e1ficas. \n- Programaci\u00f3n en Scratch.<br>\n- Actividades de dise\u00f1o e impresi\u00f3n 3D.\n- Actividades enfocadas a trabajar el pen<br>samiento computacional y a desarrollar las competencias clave para su futuro profesional y personal.<br>\n- Los alumnos est\u00e1n agrupados en parejas por niveles de tal forma que siempre realizar\u00e1n las actividades con edades similares favoreciendo el aprendizaje y la participaci\u00f3n.<br>\n- Las tareas y roles definidos cambian cada sesi\u00f3n (ingeniero, constructor, programador). Esto permite un aprendizaje muy personalizado.<br>\n- Los profesores cumplen un doble perfil: experiencia t\u00e9cnica y pedag\u00f3gica. Esto permite que las actividades extraescolares sean divertidas, con buen clima de trabajo y con un nivel t\u00e9cnico elevado.<br>\n\n<br>\n<h4 class=\"texto-azul\">D\u00edas y horas<\/h4>\nJueves de 15:00 a 16:30 h\n\n<br>\n<h4 class=\"texto-azul\">Material necesario<\/h4>\n- Material de fischertechnik (disponible)  - M\u00e1s informaci\u00f3n: <a class=\"icono enlace\" href=\"https:\/\/www.fischertechnik.de\/es-es\" target=\"_black\">www.fischertechnik.de<\/a><br>\n- Robots makeblock (disponible)\n<br>\n- Material Turing Tumble (disponible) - M\u00e1s informaci\u00f3n: <a class=\"icono enlace\" href=\"https:\/\/www.turingtumble.com\/\" target=\"_black\">www.turingtumble.com<\/a><br>\n- Creality Ender 3 Impresora 3D (disponible)<br>\n- Ordenadores aula rob\u00f3tica (disponible)<br>\n- Software RoboPro (disponible)<br>\n- Software Scratch (disponible) \n<br>\n<h4 class=\"texto-azul\">Responsable<\/h4>\nManuel Guti\u00e9rrez Pichel\n<br>\n<h4 class=\"texto-azul\">Coste<\/h4>\n40 \u20ac de mensualidad.<br>\n\n<br>\n<h4 class=\"texto-azul\">Para participar<\/h4>\nLos grupos tendr\u00e1n un m\u00ednimo de 10 alumnos y un m\u00e1ximo de 20.<br>\nLa inscripci\u00f3n se realizar\u00e1 a trav\u00e9s del formulario disponible en Sallenet.\n<br><\/div> <div role=\"tabpanel\" class=\"tab-pane\" id=\"thim-widget-tab-41778701246-1-42\"><h4 class=\"texto-azul\">Destinatarios<\/h4>\nAlumnos desde 4.\u00ba de Primaria hasta 2.\u00ba de ESO.\n<br>\n<h4 class=\"texto-azul\">Objetivos<\/h4>\nAdquirir autonom\u00eda en el  empleo de diferentes estrategias de estudio que permitan el desarrollo de aprendizajes significativos.\n<br>\n<h4 class=\"texto-azul\">Actividades que se desarrollan<\/h4>\nSe establecer\u00e1n dos fases:<br>\na) La primera centrada en abordar un marco general de las diferentes estrategias y t\u00e9cnicas de estudios, elaboraci\u00f3n de planes de trabajo semanales, etc. <br>\nb) La segunda centrada en automatizar el empleo de t\u00e9cnicas de estudio m\u00e1s adecuadas para cada participante en funci\u00f3n de sus conocimientos previos y puntos fuertes y d\u00e9biles.\n<br>\n<h4 class=\"texto-azul\">D\u00edas y horas<\/h4>\nSer\u00e1n cursos independientes de 10 horas de duraci\u00f3n. Se convocar\u00e1n dos veces al a\u00f1o.<br>\nPrimaria y Secundaria formar\u00e1n dos grupos separados\n<br>\n<h4 class=\"texto-azul\">Material necesario<\/h4>\n-\n<br>\n<h4 class=\"texto-azul\">Responsable<\/h4>\nAraceli Traba Se\u00f1ar\u00eds\n<br>\n<h4 class=\"texto-azul\">Coste<\/h4>\n-\n<br>\n<h4 class=\"texto-azul\">Para participar<\/h4>\nLos grupos tendr\u00e1n un m\u00ednimo de 7 alumnos y un m\u00e1ximo de 15.<br>\nLa inscripci\u00f3n se realizar\u00e1 a trav\u00e9s del formulario disponible en Sallenet.\n<br><\/div><\/div><\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Actividades extraescolaresActividades extraescolares del curso 2025\/26. El lunes 19 de septiembre se abrir\u00e1 un curso en SALLENET \u00abActividades Extraescolares\u00bb para poder realizar las inscripciones hasta el 26 de septiembre. Pastorales SalleXove &#8211; Grupos CristianosSalleXove &#8211; Voluntariado &#8211; Plan de Acci\u00f3n &hellip; <\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-9055","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/web.lasallesantiago.gal\/es\/wp-json\/wp\/v2\/pages\/9055","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.lasallesantiago.gal\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/web.lasallesantiago.gal\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/web.lasallesantiago.gal\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/web.lasallesantiago.gal\/es\/wp-json\/wp\/v2\/comments?post=9055"}],"version-history":[{"count":2,"href":"https:\/\/web.lasallesantiago.gal\/es\/wp-json\/wp\/v2\/pages\/9055\/revisions"}],"predecessor-version":[{"id":27709,"href":"https:\/\/web.lasallesantiago.gal\/es\/wp-json\/wp\/v2\/pages\/9055\/revisions\/27709"}],"wp:attachment":[{"href":"https:\/\/web.lasallesantiago.gal\/es\/wp-json\/wp\/v2\/media?parent=9055"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}